{"id":9325,"date":"2019-09-21T08:25:49","date_gmt":"2019-09-21T08:25:49","guid":{"rendered":"http:\/\/familytree.dirkme.de\/index.php\/georgii-christian-friedrich\/"},"modified":"2019-09-21T08:25:49","modified_gmt":"2019-09-21T08:25:49","slug":"georgii-christian-friedrich","status":"publish","type":"page","link":"https:\/\/familytree.dirkme.de\/index.php\/vorfahren-nachkommen-messerschmidt-georgii\/georgii-christian-friedrich\/","title":{"rendered":"Georgii, Christian Friedrich"},"content":{"rendered":"<section class=\"rp_truncate\"><div class=\"rp_header\" itemscope itemtype=\"https:\/\/schema.org\/Person\"><meta itemprop=\"gender\" content=\"\"\/><div float:left;\"><a href=\"http:\/\/familytree.dirkme.de\/wp-content\/plugins\/rootspersona\/\/images\/boy-silhouette.gif\"><img decoding=\"async\" class=\"rp_headerbox\" src=\"http:\/\/familytree.dirkme.de\/wp-content\/plugins\/rootspersona\/\/images\/boy-silhouette.gif\" \/><\/a><\/div><div class=\"rp_headerbox\"><span class=\"rp_headerbox\" id=\"hdr_name\" itemprop=\"name\">Private<\/span><span class=\"rp_headerbox\" style=\"padding-left:15px;text-align:right;color:#EBDDE2;display:none;\"><\/span><br\/>b: <span itemprop=\"birth\" itemscope itemtype=\"https:\/\/schema.org\/Event\"><\/span><br\/>d: <span itemprop=\"death\" itemscope itemtype=\"https:\/\/schema.org\/Event\"><\/span><\/div><\/div><\/section><div class=\"rp_banner\"><\/div>\n","protected":false},"excerpt":{"rendered":"","protected":false},"author":0,"featured_media":0,"parent":10583,"menu_order":0,"comment_status":"closed","ping_status":"open","template":"","meta":{"footnotes":""},"class_list":["post-9325","page","type-page","status-publish","hentry","comments-off"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v26.4 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Georgii, Christian Friedrich - Stammbaum Ahnenforschung Messerschmidt Georgii<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/familytree.dirkme.de\/index.php\/vorfahren-nachkommen-messerschmidt-georgii\/georgii-christian-friedrich\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Georgii, Christian Friedrich - Stammbaum Ahnenforschung Messerschmidt Georgii\" \/>\n<meta property=\"og:url\" content=\"https:\/\/familytree.dirkme.de\/index.php\/vorfahren-nachkommen-messerschmidt-georgii\/georgii-christian-friedrich\/\" \/>\n<meta property=\"og:site_name\" content=\"Stammbaum Ahnenforschung Messerschmidt Georgii\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/familytree.dirkme.de\/index.php\/vorfahren-nachkommen-messerschmidt-georgii\/georgii-christian-friedrich\/\",\"url\":\"https:\/\/familytree.dirkme.de\/index.php\/vorfahren-nachkommen-messerschmidt-georgii\/georgii-christian-friedrich\/\",\"name\":\"Georgii, Christian Friedrich - Stammbaum Ahnenforschung Messerschmidt Georgii\",\"isPartOf\":{\"@id\":\"https:\/\/familytree.dirkme.de\/#website\"},\"datePublished\":\"2019-09-21T08:25:49+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/familytree.dirkme.de\/index.php\/vorfahren-nachkommen-messerschmidt-georgii\/georgii-christian-friedrich\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/familytree.dirkme.de\/index.php\/vorfahren-nachkommen-messerschmidt-georgii\/georgii-christian-friedrich\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/familytree.dirkme.de\/index.php\/vorfahren-nachkommen-messerschmidt-georgii\/georgii-christian-friedrich\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"https:\/\/familytree.dirkme.de\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"\u03a9\",\"item\":\"https:\/\/familytree.dirkme.de\/index.php\/vorfahren-nachkommen-messerschmidt-georgii\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Georgii, Christian Friedrich\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/familytree.dirkme.de\/#website\",\"url\":\"https:\/\/familytree.dirkme.de\/\",\"name\":\"Stammbaum Ahnenforschung Messerschmidt Georgii\",\"description\":\"Family Tree History Messerschmidt Georgii Georgenau Kepler Bardili K\u00f6bberling Fl\u00fcgge Moser Zeller Alber Genealogie Vorfahren Ahnen\",\"publisher\":{\"@id\":\"https:\/\/familytree.dirkme.de\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/familytree.dirkme.de\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/familytree.dirkme.de\/#organization\",\"name\":\"Family Tree Messerschmidt Georgii Kepler Bardili K\u00f6bberling Fl\u00fcgge\",\"url\":\"https:\/\/familytree.dirkme.de\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\/\/familytree.dirkme.de\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/familytree.dirkme.de\/wp-content\/uploads\/2019\/09\/favicon2.bmp\",\"contentUrl\":\"https:\/\/familytree.dirkme.de\/wp-content\/uploads\/2019\/09\/favicon2.bmp\",\"width\":48,\"height\":48,\"caption\":\"Family Tree Messerschmidt Georgii Kepler Bardili K\u00f6bberling Fl\u00fcgge\"},\"image\":{\"@id\":\"https:\/\/familytree.dirkme.de\/#\/schema\/logo\/image\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Georgii, Christian Friedrich - Stammbaum Ahnenforschung Messerschmidt Georgii","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/familytree.dirkme.de\/index.php\/vorfahren-nachkommen-messerschmidt-georgii\/georgii-christian-friedrich\/","og_locale":"de_DE","og_type":"article","og_title":"Georgii, Christian Friedrich - Stammbaum Ahnenforschung Messerschmidt Georgii","og_url":"https:\/\/familytree.dirkme.de\/index.php\/vorfahren-nachkommen-messerschmidt-georgii\/georgii-christian-friedrich\/","og_site_name":"Stammbaum Ahnenforschung Messerschmidt Georgii","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/familytree.dirkme.de\/index.php\/vorfahren-nachkommen-messerschmidt-georgii\/georgii-christian-friedrich\/","url":"https:\/\/familytree.dirkme.de\/index.php\/vorfahren-nachkommen-messerschmidt-georgii\/georgii-christian-friedrich\/","name":"Georgii, Christian Friedrich - Stammbaum Ahnenforschung Messerschmidt Georgii","isPartOf":{"@id":"https:\/\/familytree.dirkme.de\/#website"},"datePublished":"2019-09-21T08:25:49+00:00","breadcrumb":{"@id":"https:\/\/familytree.dirkme.de\/index.php\/vorfahren-nachkommen-messerschmidt-georgii\/georgii-christian-friedrich\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/familytree.dirkme.de\/index.php\/vorfahren-nachkommen-messerschmidt-georgii\/georgii-christian-friedrich\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/familytree.dirkme.de\/index.php\/vorfahren-nachkommen-messerschmidt-georgii\/georgii-christian-friedrich\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"https:\/\/familytree.dirkme.de\/"},{"@type":"ListItem","position":2,"name":"\u03a9","item":"https:\/\/familytree.dirkme.de\/index.php\/vorfahren-nachkommen-messerschmidt-georgii\/"},{"@type":"ListItem","position":3,"name":"Georgii, Christian Friedrich"}]},{"@type":"WebSite","@id":"https:\/\/familytree.dirkme.de\/#website","url":"https:\/\/familytree.dirkme.de\/","name":"Stammbaum Ahnenforschung Messerschmidt Georgii","description":"Family Tree History Messerschmidt Georgii Georgenau Kepler Bardili K\u00f6bberling Fl\u00fcgge Moser Zeller Alber Genealogie Vorfahren Ahnen","publisher":{"@id":"https:\/\/familytree.dirkme.de\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/familytree.dirkme.de\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Organization","@id":"https:\/\/familytree.dirkme.de\/#organization","name":"Family Tree Messerschmidt Georgii Kepler Bardili K\u00f6bberling Fl\u00fcgge","url":"https:\/\/familytree.dirkme.de\/","logo":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/familytree.dirkme.de\/#\/schema\/logo\/image\/","url":"https:\/\/familytree.dirkme.de\/wp-content\/uploads\/2019\/09\/favicon2.bmp","contentUrl":"https:\/\/familytree.dirkme.de\/wp-content\/uploads\/2019\/09\/favicon2.bmp","width":48,"height":48,"caption":"Family Tree Messerschmidt Georgii Kepler Bardili K\u00f6bberling Fl\u00fcgge"},"image":{"@id":"https:\/\/familytree.dirkme.de\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/familytree.dirkme.de\/index.php\/wp-json\/wp\/v2\/pages\/9325","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/familytree.dirkme.de\/index.php\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/familytree.dirkme.de\/index.php\/wp-json\/wp\/v2\/types\/page"}],"replies":[{"embeddable":true,"href":"https:\/\/familytree.dirkme.de\/index.php\/wp-json\/wp\/v2\/comments?post=9325"}],"version-history":[{"count":0,"href":"https:\/\/familytree.dirkme.de\/index.php\/wp-json\/wp\/v2\/pages\/9325\/revisions"}],"up":[{"embeddable":true,"href":"https:\/\/familytree.dirkme.de\/index.php\/wp-json\/wp\/v2\/pages\/10583"}],"wp:attachment":[{"href":"https:\/\/familytree.dirkme.de\/index.php\/wp-json\/wp\/v2\/media?parent=9325"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}